{"id":13918,"date":"2022-09-21T10:58:00","date_gmt":"2022-09-21T13:58:00","guid":{"rendered":"https:\/\/meunegocio.uol.com.br\/blog\/?p=13918"},"modified":"2026-01-13T10:55:07","modified_gmt":"2026-01-13T13:55:07","slug":"o-que-significa-dominio-congelado","status":"publish","type":"post","link":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/","title":{"rendered":"O que significa dom\u00ednio congelado?"},"content":{"rendered":"\n<p>A vida do empreendedor \u00e9 cercada de imprevistos, principalmente quando \u00e9 preciso lidar com as funcionalidades do universo virtual. <strong>Ao vender pela internet voc\u00ea pode ter mais praticidade e alcance de p\u00fablico<\/strong>, mas tamb\u00e9m precisa ter aten\u00e7\u00e3o redobrada a alguns prazos que evitam preju\u00edzos.<\/p>\n\n\n\n<p><strong>A renova\u00e7\u00e3o do seu dom\u00ednio<\/strong>, por exemplo, \u00e9 um dos itens que devem estar marcados na sua lista de prioridades. Isso mesmo, n\u00e3o basta escolher o endere\u00e7o virtual perfeito para a sua marca, tamb\u00e9m \u00e9 fundamental <strong>renov\u00e1-lo para garantir que voc\u00ea possa fazer uso dele por muito tempo<\/strong>. Caso contr\u00e1rio, voc\u00ea corre o risco de ter o seu<strong> dom\u00ednio congelado<\/strong>!<\/p>\n\n\n\n<p>J\u00e1 ouviu falar desse termo? Apesar de causar arrepios em muitos empreendedores, o dom\u00ednio congelado pode ser considerado uma prote\u00e7\u00e3o \u00e0 URL do seu site.<\/p>\n\n\n\n<p>Isso porque quando o <a href=\"https:\/\/meunegocio.uol.com.br\/blog\/o-que-e-dominio\/\">dom\u00ednio<\/a> n\u00e3o \u00e9 renovado \u2013 seja qual for o motivo \u2013, esse \u201cstatus\u201d protege sua empresa, impedindo que outras pessoas registrem o mesmo dom\u00ednio enquanto a situa\u00e7\u00e3o n\u00e3o \u00e9 regularizada.<\/p>\n\n\n\n<p><strong>O ideal \u00e9 que voc\u00ea n\u00e3o perca o prazo de renova\u00e7\u00e3o do seu dom\u00ednio<\/strong>, mas o UOL Meu Neg\u00f3cio entende que imprevistos acontecem. Por isso, criamos um conte\u00fado especial para quem est\u00e1 passando por essa situa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Comece a leitura agora mesmo e fique por dentro desse assunto!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dom\u00ednio Congelado: o que significa isso?&nbsp;<\/h2>\n\n\n\n<p>Se voc\u00ea quer saber o que significa o status \u201ccongelado\u201d no <a href=\"https:\/\/registro.br\/\"><em>Registro.br<\/em><\/a>, n\u00f3s temos a resposta! O termo \u201cdom\u00ednio congelado\u201d <strong>se refere aos <\/strong><a href=\"https:\/\/meunegocio.uol.com.br\/blog\/por-que-um-dominio-personalizado-aumenta-a-sua-presenca-digital\/\"><strong>dom\u00ednios<\/strong><\/a><strong> que possuem alguma pend\u00eancia de pagamento e acabam expirando.<\/strong><\/p>\n\n\n\n<p>Ap\u00f3s 14 dias, o acesso ao site, o banco de dados e o envio\/recebimento de e-mails ficam bloqueados. Portanto, \u00e9 fundamental ter <strong>aten\u00e7\u00e3o ao prazo de renova\u00e7\u00e3o do seu dom\u00ednio<\/strong> para evitar esse tipo de preju\u00edzo.<\/p>\n\n\n\n<p>Agora, se voc\u00ea j\u00e1 estiver com o dom\u00ednio congelado e os acessos bloqueados, \u00e9 importante saber que<strong> voc\u00ea tem o prazo m\u00e1ximo de 90 dias para pagar a renova\u00e7\u00e3o e regularizar a situa\u00e7\u00e3o com o provedor<\/strong>.<\/p>\n\n\n\n<p>Caso contr\u00e1rio, o seu dom\u00ednio fica liberado para ser utilizado em um novo registro!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como saber se meu dom\u00ednio est\u00e1 congelado?<\/h3>\n\n\n\n<p>Para dom\u00ednios registrados no <em>Registro.br, <\/em>a verifica\u00e7\u00e3o pode ser feita em menos de 1 minuto. Primeiro, acesse o <a href=\"https:\/\/registro.br\/\">site do \u00f3rg\u00e3o<\/a> e clique na aba \u201c<strong>Tecnologia<\/strong>\u201d, na parte superior da tela, e depois em \u201c<strong>Ferramentas<\/strong>\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"384\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1-1024x384.jpeg\" alt=\"\" class=\"wp-image-13926\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1-1024x384.jpeg 1024w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1-300x113.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1-768x288.jpeg 768w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1-1536x576.jpeg 1536w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img1.jpeg 1847w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Na p\u00e1gina seguinte, clique em \u201c<strong>Servi\u00e7o de diret\u00f3rio whois<\/strong>\u201d. No campo \u201c<strong>Fa\u00e7a a sua consulta<\/strong>\u201d, digite o seu dom\u00ednio para que a verifica\u00e7\u00e3o possa ser feita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"482\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2-1024x482.jpeg\" alt=\"\" class=\"wp-image-13920\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2-1024x482.jpeg 1024w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2-300x141.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2-768x362.jpeg 768w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2-1536x723.jpeg 1536w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img2.jpeg 1663w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3-1024x518.jpeg\" alt=\"\" class=\"wp-image-13921\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3-1024x518.jpeg 1024w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3-300x152.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3-768x388.jpeg 768w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3-1536x776.jpeg 1536w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img3.jpeg 1725w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Pronto! Nas informa\u00e7\u00f5es geradas, procure pelo item \u201c<strong>Status<\/strong>\u201d e saiba se o seu dom\u00ednio est\u00e1 \u201c<strong>Congelado<\/strong>\u201d ou \u201c<strong>Publicado<\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"741\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img4.jpeg\" alt=\"\" class=\"wp-image-13922\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img4.jpeg 681w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img4-276x300.jpeg 276w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Como descongelar um dom\u00ednio?<\/h3>\n\n\n\n<p>O <em>Registro.br<\/em> \u00e9 o \u00f3rg\u00e3o respons\u00e1vel por <a href=\"https:\/\/meunegocio.uol.com.br\/blog\/registrar-varios-dominios-para-o-seu-site-entenda-porque-voce-deve-fazer-isso\/\">registrar todos os dom\u00ednios<\/a> nacionais que possuem a extens\u00e3o \u201c<strong>.br<\/strong>\u201d. Portanto, para descongelar um dom\u00ednio, \u00e9 necess\u00e1rio acessar o <a href=\"https:\/\/registro.br\/\">site da empresa<\/a> e iniciar um passo a passo. Mas fique tranquilo(a), o processo n\u00e3o \u00e9 muito trabalhoso.<\/p>\n\n\n\n<p>Primeiro, role a p\u00e1gina principal e procure a se\u00e7\u00e3o &#8220;Fique atento!&#8221;. Em seguida, procure pelo item &#8220;<strong>Seu dom\u00ednio expirou?<\/strong>&#8221; e clique na op\u00e7\u00e3o &#8220;Estender publica\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"392\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img5-1024x392.jpeg\" alt=\"\" class=\"wp-image-13923\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img5-1024x392.jpeg 1024w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img5-300x115.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img5-768x294.jpeg 768w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img5.jpeg 1221w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Na p\u00e1gina seguinte, voc\u00ea poder\u00e1 solicitar a extens\u00e3o do prazo de pagamento, informando o nome do dom\u00ednio congelado que deseja utilizar novamente (informe o seu dom\u00ednio sem o \u201cwww\u201d). Depois, clique no bot\u00e3o \u201c<strong>Avan\u00e7ar<\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"567\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img6.jpeg\" alt=\"\" class=\"wp-image-13924\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img6.jpeg 905w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img6-300x188.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img6-768x481.jpeg 768w\" sizes=\"auto, (max-width: 905px) 100vw, 905px\" \/><\/figure>\n\n\n\n<p>Por fim, o <em>Registro.br<\/em> vai solicitar alguns dados para confirma\u00e7\u00e3o, como nome completo, e-mail e n\u00famero de telefone. Voc\u00ea tamb\u00e9m deve justificar um motivo para o n\u00e3o pagamento da renova\u00e7\u00e3o do dom\u00ednio. Depois de inserir os dados, basta clicar no bot\u00e3o &#8220;Enviar pedido&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"905\" height=\"900\" src=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img7.jpeg\" alt=\"\" class=\"wp-image-13925\" srcset=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img7.jpeg 905w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img7-300x298.jpeg 300w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img7-150x150.jpeg 150w, https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/dominio-congelado-img7-768x764.jpeg 768w\" sizes=\"auto, (max-width: 905px) 100vw, 905px\" \/><\/figure>\n\n\n\n<p>Fique de olho no seu e-mail, \u00e9 por l\u00e1 que voc\u00ea receber\u00e1 o link para descongelar o seu dom\u00ednio. Basta clicar nele e em poucos minutos o dom\u00ednio congelado volta ao status &#8220;publicado&#8221;, com todas as funcionalidades habilitadas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por qual motivo \u00e9 importante n\u00e3o deixar que seu dom\u00ednio seja congelado?<\/h2>\n\n\n\n<p>Se voc\u00ea vende apenas pela internet ou tem uma p\u00e1gina para o seu neg\u00f3cio f\u00edsico, j\u00e1 deve saber a import\u00e2ncia de um site que funcione 24h por dia, n\u00e3o \u00e9 mesmo? Por isso, \u00e9 fundamental que o seu dom\u00ednio n\u00e3o seja congelado.<\/p>\n\n\n\n<p>Ao ficar atento(a) ao prazo de renova\u00e7\u00e3o do seu dom\u00ednio, a sua p\u00e1gina n\u00e3o corre risco algum de sair do ar! J\u00e1 pensou no preju\u00edzo em vendas que isso pode causar?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9 poss\u00edvel registrar um dom\u00ednio congelado?<\/h2>\n\n\n\n<p>A resposta \u00e9 n\u00e3o. No caso dos dom\u00ednios nacionais (.br), o propriet\u00e1rio tem o prazo de 104 dias para acertar a pend\u00eancia e regularizar a situa\u00e7\u00e3o. Ap\u00f3s esse per\u00edodo, <strong>o dom\u00ednio congelado ficar\u00e1 indispon\u00edvel<\/strong>, n\u00e3o sendo poss\u00edvel um outro registro imediato.&nbsp;<\/p>\n\n\n\n<p>A partir da\u00ed, o dom\u00ednio fica em &#8220;Processo de Libera\u00e7\u00e3o&#8221;, podendo levar meses ou at\u00e9 anos para que fique dispon\u00edvel para novos propriet\u00e1rios. Os interessados no novo registro poder\u00e3o participar de um leil\u00e3o onde quem paga mais fica com o dom\u00ednio!<\/p>\n\n\n\n<p>O processo para dom\u00ednios globais \u00e9 semelhante. Ap\u00f3s o vencimento, o dom\u00ednio fica indispon\u00edvel e entra na \u201cFase de Reden\u00e7\u00e3o&#8221;, que pode durar at\u00e9 45 dias. Depois, o dom\u00ednio pode ser imediatamente negociado em leil\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como evitar o congelamento do meu dom\u00ednio?&nbsp;<\/h2>\n\n\n\n<p>Um dos principais motivos para o congelamento de um dom\u00ednio \u00e9 a falta de pagamento. Ou seja, o prazo de renova\u00e7\u00e3o do dom\u00ednio expira e o propriet\u00e1rio acaba tendo todas as funcionalidades do site e <a href=\"https:\/\/meunegocio.uol.com.br\/blog\/registro-de-dominio-e-e-mail-marketing\/\">e-mail<\/a> bloqueados.<\/p>\n\n\n\n<p>Por isso, uma a\u00e7\u00e3o que pode ser bem \u00fatil para voc\u00ea evitar os esquecimentos \u00e9 o registro do dom\u00ednio no mesmo local da <a href=\"https:\/\/meunegocio.uol.com.br\/blog\/qual-a-diferenca-entre-dominio-e-hospedagem\/\">hospedagem<\/a>. Dessa forma, com apenas um login, \u00e9 poss\u00edvel acessar os pain\u00e9is de hospedagem e registro em um mesmo lugar.<\/p>\n\n\n\n<p>Sabe onde voc\u00ea encontra essa alternativa bem vantajosa?<strong> Com o <\/strong><a href=\"https:\/\/meunegocio.uol.com.br\/blog\/registro-de-dominio-uolmeunegocio\/\"><strong>UOL Meu Neg\u00f3cio<\/strong><\/a><strong>!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Registro de Dom\u00ednio \u00e9 com UOL Meu Neg\u00f3cio!<\/h2>\n\n\n\n<p><strong>O UOL Meu Neg\u00f3cio \u00e9 o seu parceiro para facilitar todos os processos.<\/strong> E para evitar que o seu neg\u00f3cio tenha o dom\u00ednio congelado, n\u00e3o poderia ser diferente!<\/p>\n\n\n\n<p>Fa\u00e7a j\u00e1 o <a href=\"https:\/\/meunegocio.uol.com.br\/registro-de-dominio\"><strong>Registro de Dom\u00ednio<\/strong><\/a> do seu site e leve uma caixa de email de 12GB, sem pagar nada a mais por isso! E mais, garanta a exclusividade da sua marca na internet, tenha acesso a um painel completo, e tenha todas as informa\u00e7\u00f5es que voc\u00ea precisa na palma da sua m\u00e3o!<\/p>\n\n\n\n<p>Assim, voc\u00ea garante a renova\u00e7\u00e3o do seu dom\u00ednio no prazo certo. Acesse o nosso site e saiba mais!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vida do empreendedor \u00e9 cercada de imprevistos, principalmente quando \u00e9 preciso lidar com as funcionalidades do universo virtual. Ao vender pela internet voc\u00ea pode ter mais praticidade e alcance de p\u00fablico, mas tamb\u00e9m precisa ter aten\u00e7\u00e3o redobrada a alguns prazos que evitam preju\u00edzos. A renova\u00e7\u00e3o do seu dom\u00ednio, por exemplo, \u00e9 um dos itens [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":13928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1468,64,1444,33],"tags":[1175],"class_list":["post-13918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desenvolvimento-web","category-dominio","category-fundamentos-web","category-presenca-digital","tag-registrodedominio"],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu<\/title>\n<meta name=\"description\" content=\"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T13:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T13:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"979\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yuri Torres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yuri Torres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\"},\"author\":{\"name\":\"Yuri Torres\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/41505c2cd07dc07109e30bea51edee93\"},\"headline\":\"O que significa dom\u00ednio congelado?\",\"datePublished\":\"2022-09-21T13:58:00+00:00\",\"dateModified\":\"2026-01-13T13:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\"},\"wordCount\":1152,\"publisher\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr\",\"keywords\":[\"registrodedominio\"],\"articleSection\":[\"Desenvolvimento Web\",\"Dom\u00ednio\",\"Fundamentos Web\",\"Presen\u00e7a digital\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\",\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\",\"name\":\"Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu\",\"isPartOf\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr\",\"datePublished\":\"2022-09-21T13:58:00+00:00\",\"dateModified\":\"2026-01-13T13:55:07+00:00\",\"description\":\"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!\",\"breadcrumb\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage\",\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr\",\"contentUrl\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr\",\"width\":979,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/uolhost.uol.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que significa dom\u00ednio congelado?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#website\",\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/\",\"name\":\"Blog UOL Host\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uolhost.uol.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#organization\",\"name\":\"Blog UOL Host\",\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2025\/01\/UOL_Host.png?wsr\",\"contentUrl\":\"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2025\/01\/UOL_Host.png?wsr\",\"width\":2000,\"height\":393,\"caption\":\"Blog UOL Host\"},\"image\":{\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/41505c2cd07dc07109e30bea51edee93\",\"name\":\"Yuri Torres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c96a05faea9fdf86f95d5b723e438c9cc14ad5c342d76486e5a4c8ac8259492?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c96a05faea9fdf86f95d5b723e438c9cc14ad5c342d76486e5a4c8ac8259492?s=96&d=mm&r=g\",\"caption\":\"Yuri Torres\"},\"description\":\"Profissional de Reda\u00e7\u00e3o e Marketing, com 10 anos de experi\u00eancia no desenvolvimento de estrat\u00e9gias de conte\u00fado voltadas \u00e0 comunica\u00e7\u00e3o de marcas. Atua na cria\u00e7\u00e3o de materiais que fortalecem a presen\u00e7a digital, ampliam o engajamento e contribuem para o alcance de resultados alinhados aos objetivos de neg\u00f3cio, com experi\u00eancia no atendimento a empresas de diferentes segmentos. LinkedIn\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/yuri-torres-271093108\/\"],\"url\":\"https:\/\/uolhost.uol.com.br\/blog\/author\/yuri-torres\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu","description":"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/","og_locale":"pt_BR","og_type":"article","og_title":"Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu","og_description":"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!","og_url":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/","article_published_time":"2022-09-21T13:58:00+00:00","article_modified_time":"2026-01-13T13:55:07+00:00","og_image":[{"width":979,"height":450,"url":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png","type":"image\/png"}],"author":"Yuri Torres","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Yuri Torres","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#article","isPartOf":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/"},"author":{"name":"Yuri Torres","@id":"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/41505c2cd07dc07109e30bea51edee93"},"headline":"O que significa dom\u00ednio congelado?","datePublished":"2022-09-21T13:58:00+00:00","dateModified":"2026-01-13T13:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/"},"wordCount":1152,"publisher":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage"},"thumbnailUrl":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr","keywords":["registrodedominio"],"articleSection":["Desenvolvimento Web","Dom\u00ednio","Fundamentos Web","Presen\u00e7a digital"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/","url":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/","name":"Dom\u00ednio Congelado: Saiba o que \u00e9 e como descongelar o seu","isPartOf":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage"},"image":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage"},"thumbnailUrl":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr","datePublished":"2022-09-21T13:58:00+00:00","dateModified":"2026-01-13T13:55:07+00:00","description":"Voc\u00ea sabe qual \u00e9 a data de vencimento do dom\u00ednio do seu site? Se ainda n\u00e3o, vamos mostrar a import\u00e2ncia da renova\u00e7\u00e3o para evitar o temido dom\u00ednio congelado!","breadcrumb":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#primaryimage","url":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr","contentUrl":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2022\/09\/o-que-significa-dominio-congelado_.png?wsr","width":979,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/uolhost.uol.com.br\/blog\/o-que-significa-dominio-congelado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/uolhost.uol.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que significa dom\u00ednio congelado?"}]},{"@type":"WebSite","@id":"https:\/\/uolhost.uol.com.br\/blog\/#website","url":"https:\/\/uolhost.uol.com.br\/blog\/","name":"Blog UOL Host","description":"","publisher":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uolhost.uol.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/uolhost.uol.com.br\/blog\/#organization","name":"Blog UOL Host","url":"https:\/\/uolhost.uol.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2025\/01\/UOL_Host.png?wsr","contentUrl":"https:\/\/uolhost.uol.com.br\/blog\/wp-content\/uploads\/2025\/01\/UOL_Host.png?wsr","width":2000,"height":393,"caption":"Blog UOL Host"},"image":{"@id":"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/41505c2cd07dc07109e30bea51edee93","name":"Yuri Torres","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/uolhost.uol.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c96a05faea9fdf86f95d5b723e438c9cc14ad5c342d76486e5a4c8ac8259492?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c96a05faea9fdf86f95d5b723e438c9cc14ad5c342d76486e5a4c8ac8259492?s=96&d=mm&r=g","caption":"Yuri Torres"},"description":"Profissional de Reda\u00e7\u00e3o e Marketing, com 10 anos de experi\u00eancia no desenvolvimento de estrat\u00e9gias de conte\u00fado voltadas \u00e0 comunica\u00e7\u00e3o de marcas. Atua na cria\u00e7\u00e3o de materiais que fortalecem a presen\u00e7a digital, ampliam o engajamento e contribuem para o alcance de resultados alinhados aos objetivos de neg\u00f3cio, com experi\u00eancia no atendimento a empresas de diferentes segmentos. LinkedIn","sameAs":["https:\/\/www.linkedin.com\/in\/yuri-torres-271093108\/"],"url":"https:\/\/uolhost.uol.com.br\/blog\/author\/yuri-torres\/"}]}},"_links":{"self":[{"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/posts\/13918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/comments?post=13918"}],"version-history":[{"count":1,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/posts\/13918\/revisions"}],"predecessor-version":[{"id":19005,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/posts\/13918\/revisions\/19005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/media\/13928"}],"wp:attachment":[{"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uolhost.uol.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}